{"id":5115,"date":"2025-01-23T21:39:49","date_gmt":"2025-01-23T21:39:49","guid":{"rendered":"https:\/\/nyschildrensasthma.org\/?page_id=5115"},"modified":"2026-04-28T14:03:42","modified_gmt":"2026-04-28T14:03:42","slug":"asthma-remediation-hrsn-services","status":"publish","type":"page","link":"https:\/\/nyschildrensasthma.org\/fr\/asthma-remediation-hrsn-services\/","title":{"rendered":"Rem\u00e9diation \u00e0 l'asthme Services HRSN"},"content":{"rendered":"<div data-elementor-type=\"wp-post\" data-elementor-id=\"5115\" class=\"elementor elementor-5115\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-33571388 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"33571388\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;shape_divider_bottom&quot;:&quot;tilt&quot;}\">\n\t\t\t\t\t<div class=\"elementor-shape elementor-shape-bottom\" aria-hidden=\"true\" data-negative=\"false\">\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewbox=\"0 0 1000 100\" preserveaspectratio=\"none\">\n\t<path class=\"elementor-shape-fill\" d=\"M0,6V0h1000v100L0,6z\"\/>\n<\/svg>\t\t<\/div>\n\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-3b75b2fc\" data-id=\"3b75b2fc\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-7df7f641 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"7df7f641\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-27e8bb34\" data-id=\"27e8bb34\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6421586b elementor-widget-mobile__width-initial elementor-widget elementor-widget-heading\" data-id=\"6421586b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Rem\u00e9diation \u00e0 l'asthme Services HRSN<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1f771502 elementor-widget-divider--separator-type-pattern elementor-widget-divider--no-spacing elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"1f771502\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\" style=\"--divider-pattern-url: url(&quot;data:image\/svg+xml,%3Csvg xmlns=&#039;http:\/\/www.w3.org\/2000\/svg&#039; preserveAspectRatio=&#039;xMidYMid meet&#039; overflow=&#039;visible&#039; height=&#039;100%&#039; viewBox=&#039;0 0 126 26&#039; fill=&#039;black&#039; stroke=&#039;none&#039;%3E%3Cpath d=&#039;M3,10.2c2.6,0,2.6,2,2.6,3.2S4.4,16.5,3,16.5s-3-1.4-3-3.2S0.4,10.2,3,10.2z M18.8,10.2c1.7,0,3.2,1.4,3.2,3.2s-1.4,3.2-3.2,3.2c-1.7,0-3.2-1.4-3.2-3.2S17,10.2,18.8,10.2z M34.6,10.2c1.5,0,2.6,1.4,2.6,3.2s-0.5,3.2-1.9,3.2c-1.5,0-3.4-1.4-3.4-3.2S33.1,10.2,34.6,10.2z M50.5,10.2c1.7,0,3.2,1.4,3.2,3.2s-1.4,3.2-3.2,3.2c-1.7,0-3.3-0.9-3.3-2.6S48.7,10.2,50.5,10.2z M66.2,10.2c1.5,0,3.4,1.4,3.4,3.2s-1.9,3.2-3.4,3.2c-1.5,0-2.6-0.4-2.6-2.1S64.8,10.2,66.2,10.2z M82.2,10.2c1.7,0.8,2.6,1.4,2.6,3.2s-0.1,3.2-1.6,3.2c-1.5,0-3.7-1.4-3.7-3.2S80.5,9.4,82.2,10.2zM98.6,10.2c1.5,0,2.6,0.4,2.6,2.1s-1.2,4.2-2.6,4.2c-1.5,0-3.7-0.4-3.7-2.1S97.1,10.2,98.6,10.2z M113.4,10.2c1.2,0,2.2,0.9,2.2,3.2s-0.1,3.2-1.3,3.2s-3.1-1.4-3.1-3.2S112.2,10.2,113.4,10.2z&#039;\/%3E%3C\/svg%3E&quot;);\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4d2a91e elementor-widget__width-initial elementor-widget-mobile__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"4d2a91e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Les services de rem\u00e9diation de l'asthme NYHER sont destin\u00e9s \u00e0 traiter les multiples d\u00e9clencheurs d'asthme dans l'environnement domestique afin d'am\u00e9liorer la r\u00e9sidence du membre b\u00e9n\u00e9ficiaire et sa capacit\u00e9 d'autogestion de l'asthme. Ils comprennent une \u00e9ducation \u00e0 l'autogestion de l'asthme, des services d'assainissement pour \u00e9liminer les allerg\u00e8nes de l'environnement int\u00e9rieur et la diffusion de produits de soutien pour \u00e9liminer ou r\u00e9duire les d\u00e9clencheurs de l'asthme au domicile du membre. Les services seront adapt\u00e9s aux besoins individuels du membre et \u00e0 sa r\u00e9sidence principale (logement occup\u00e9 par son propri\u00e9taire ou logement locatif).<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-6677cb29\" data-id=\"6677cb29\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6543709 elementor-widget elementor-widget-image\" data-id=\"6543709\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"768\" height=\"518\" src=\"https:\/\/nyschildrensasthma.org\/wp-content\/uploads\/2025\/01\/2148457028-768x518.jpg\" class=\"attachment-medium_large size-medium_large wp-image-5117\" alt=\"\" srcset=\"https:\/\/nyschildrensasthma.org\/wp-content\/uploads\/2025\/01\/2148457028-768x518.jpg 768w, https:\/\/nyschildrensasthma.org\/wp-content\/uploads\/2025\/01\/2148457028-300x202.jpg 300w, https:\/\/nyschildrensasthma.org\/wp-content\/uploads\/2025\/01\/2148457028.jpg 1000w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-5057dc1 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"5057dc1\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-133975c\" data-id=\"133975c\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2a6ec56 elementor-widget elementor-widget-heading\" data-id=\"2a6ec56\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Qui peut b\u00e9n\u00e9ficier des services de rem\u00e9diation de l'asthme ?<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-40560fe elementor-widget__width-inherit elementor-widget elementor-widget-text-editor\" data-id=\"40560fe\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>1) L'adh\u00e9rent appartient \u00e0 une ou plusieurs populations couvertes (renforc\u00e9es).<\/p><p>2) Identifi\u00e9s lors du d\u00e9pistage HRSN des communaut\u00e9s de sant\u00e9 responsables comme pr\u00e9sentant des facteurs de risque HRSN non satisfaits li\u00e9s au logement.<\/p><p>3) N\u00e9cessite un service de modification\/rem\u00e9diation du domicile cliniquement appropri\u00e9<\/p><p>4) a un \u00e9tat de sant\u00e9 qui est aggrav\u00e9 par l'environnement physique de l'individu<\/p><p>5) a re\u00e7u un diagnostic d'asthme et remplit les crit\u00e8res cliniques suppl\u00e9mentaires suivants :<\/p><ul><li>Une ou plusieurs hospitalisations li\u00e9es \u00e0 l'asthme au cours des 12 derniers mois ; ou<\/li><li>Deux visites ou plus aux urgences li\u00e9es \u00e0 l'asthme au cours des 12 derniers mois ; ou<\/li><li>Trois visites ou plus aux soins d'urgence li\u00e9es \u00e0 l'asthme au cours des 12 derniers mois ; ou<\/li><li>Deux prescriptions ou plus pour l'utilisation de st\u00e9ro\u00efdes oraux en rapport avec un diagnostic d'asthme au cours des 12 derniers mois ; ou<\/li><li>Trois \u00e0 onze cas de prescription d'un inhalateur de secours, y compris l'albut\u00e9rol, au cours des 12 derniers mois.<\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a7eb976 elementor-widget elementor-widget-text-editor\" data-id=\"a7eb976\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><em>Le navigateur de l'aide sociale est tenu de documenter les crit\u00e8res cliniques de qualification pour la rem\u00e9diation de l'asthme dans le <\/em><em>Plan d'aide sociale de l'adh\u00e9rent.<\/em><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t<div class=\"elementor-element elementor-element-507134f e-flex e-con-boxed e-con e-parent\" data-id=\"507134f\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-355952c elementor-widget elementor-widget-heading\" data-id=\"355952c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Rem\u00e9diation \u00e0 l'asthme Services HRSN am\u00e9lior\u00e9s <\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-262d908 elementor-widget elementor-widget-text-editor\" data-id=\"262d908\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"font-weight: 400;\"><strong>2.3\u00a0 <\/strong><\/span><span style=\"font-weight: 400;\">Rem\u00e9diation de l'asthme<\/span><\/p><ul><li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\"><strong>Composant A<\/strong>: \u00c9ducation \u00e0 l'autogestion de l'asthme (ASME)<\/span><\/li><li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\"><strong>Composant B<\/strong>: \u00c9valuation des logements et \u00e9laboration du cahier des charges (y compris l'examen technique du cahier des charges)<\/span><\/li><li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\"><strong>Composant C<\/strong>: Assainissement des habitations et fourniture de produits de soutien<\/span><\/li><li aria-level=\"1\"><strong>Composante D :<\/strong> Assurance de la qualit\u00e9 (AQ) Inspection<\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-1f097b0 e-flex e-con-boxed e-con e-parent\" data-id=\"1f097b0\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-512b994 e-n-tabs-mobile elementor-widget elementor-widget-n-tabs\" data-id=\"512b994\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;tabs_justify_horizontal&quot;:&quot;stretch&quot;,&quot;horizontal_scroll&quot;:&quot;disable&quot;}\" data-widget_type=\"nested-tabs.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"e-n-tabs\" data-widget-number=\"85113236\" aria-label=\"Schede. Apri gli elementi con Invio o Spazio, chiudili con Esc e naviga con i tasti freccia.\" data-no-translation-aria-label=\"\">\n\t\t\t<div class=\"e-n-tabs-heading\" role=\"tablist\">\n\t\t\t\t\t<button id=\"e-n-tab-title-851132361\" data-tab-title-id=\"e-n-tab-title-851132361\" class=\"e-n-tab-title\" aria-selected=\"true\" data-tab-index=\"1\" role=\"tab\" tabindex=\"0\" aria-controls=\"e-n-tab-content-851132361\" style=\"--n-tabs-title-order: 1;\">\n\t\t\t\t\t\t<span class=\"e-n-tab-title-text\">\n\t\t\t\tA\t\t\t<\/span>\n\t\t<\/button>\n\t\t\t\t<button id=\"e-n-tab-title-851132362\" data-tab-title-id=\"e-n-tab-title-851132362\" class=\"e-n-tab-title\" aria-selected=\"false\" data-tab-index=\"2\" role=\"tab\" tabindex=\"-1\" aria-controls=\"e-n-tab-content-851132362\" style=\"--n-tabs-title-order: 2;\">\n\t\t\t\t\t\t<span class=\"e-n-tab-title-text\">\n\t\t\t\tB\t\t\t<\/span>\n\t\t<\/button>\n\t\t\t\t<button id=\"e-n-tab-title-851132363\" data-tab-title-id=\"e-n-tab-title-851132363\" class=\"e-n-tab-title\" aria-selected=\"false\" data-tab-index=\"3\" role=\"tab\" tabindex=\"-1\" aria-controls=\"e-n-tab-content-851132363\" style=\"--n-tabs-title-order: 3;\">\n\t\t\t\t\t\t<span class=\"e-n-tab-title-text\">\n\t\t\t\tC\t\t\t<\/span>\n\t\t<\/button>\n\t\t\t\t<button id=\"e-n-tab-title-851132364\" data-tab-title-id=\"e-n-tab-title-851132364\" class=\"e-n-tab-title\" aria-selected=\"false\" data-tab-index=\"4\" role=\"tab\" tabindex=\"-1\" aria-controls=\"e-n-tab-content-851132364\" style=\"--n-tabs-title-order: 4;\">\n\t\t\t\t\t\t<span class=\"e-n-tab-title-text\">\n\t\t\t\tD\t\t\t<\/span>\n\t\t<\/button>\n\t\t\t\t\t<\/div>\n\t\t\t<div class=\"e-n-tabs-content\">\n\t\t\t\t<div id=\"e-n-tab-content-851132361\" role=\"tabpanel\" aria-labelledby=\"e-n-tab-title-851132361\" data-tab-index=\"1\" style=\"--n-tabs-title-order: 1;\" class=\"e-active elementor-element elementor-element-dd37aa2 e-con-full e-flex e-con e-child\" data-id=\"dd37aa2\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-9d0f185 elementor-widget elementor-widget-heading\" data-id=\"9d0f185\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">\u00c9ducation \u00e0 l'autogestion de l'asthme (ASME)<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-41d3c0c elementor-widget elementor-widget-text-editor\" data-id=\"41d3c0c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>L'ASME est une \u00e9ducation \u00e0 la sant\u00e9 adapt\u00e9e aux besoins du membre et de sa famille\/soignants afin d'\u00e9largir les connaissances sur l'asthme, telles que les signes d'alerte pr\u00e9coce et la gestion de l'aggravation des sympt\u00f4mes, le contr\u00f4le de l'asthme et l'observance des m\u00e9dicaments, ainsi que l'identification et la r\u00e9duction des d\u00e9clencheurs de l'asthme. L'ASME doit \u00eatre men\u00e9e en conformit\u00e9 avec les directives nationales sur l'asthme et soutenir l'\u00e9ducation en vue d'un partenariat dans le traitement de l'asthme.<\/p><p><strong>L'ASME doit comprendre une \u00e9valuation de l'asthme et de la sant\u00e9 environnementale \u00e0 domicile, r\u00e9alis\u00e9e lors de deux visites distinctes :<\/strong><\/p><p><strong>Visite initiale<\/strong>La visite initiale doit \u00eatre effectu\u00e9e en personne dans le logement du membre afin de fournir une \u00e9valuation initiale de l'asthme et de l'environnement domestique et de s'assurer de la pertinence des services de rem\u00e9diation de l'asthme. La visite initiale doit permettre d'identifier les connaissances, les comp\u00e9tences et les besoins du membre\/de l'aidant en mati\u00e8re d'asthme, de d\u00e9terminer le contr\u00f4le de l'asthme en administrant et en notant un questionnaire de d\u00e9pistage du contr\u00f4le de l'asthme valid\u00e9 et adapt\u00e9 \u00e0 l'\u00e2ge (ACT, C-ACT, TRACK), et de fournir une \u00e9ducation sur les facteurs environnementaux \u00e0 domicile et les d\u00e9clencheurs susceptibles d'avoir un impact sur l'asthme.<\/p><p><strong>Visite finale :<\/strong> peut \u00eatre effectu\u00e9e en personne dans le logement du membre ou en face \u00e0 face virtuel (par exemple, par appel vid\u00e9o) et doit avoir lieu au plus t\u00f4t 45 jours apr\u00e8s l'ach\u00e8vement de tous les services de remise en \u00e9tat du logement. Dans les rares cas o\u00f9 le membre ne permet pas une visite finale en personne ou virtuellement, la visite finale peut \u00eatre effectu\u00e9e par t\u00e9l\u00e9phone. La derni\u00e8re visite doit comprendre des \u00e9valuations de l'asthme et de l'environnement domestique, l'administration et la notation d'un questionnaire de contr\u00f4le de l'asthme valid\u00e9 et adapt\u00e9 \u00e0 l'\u00e2ge (ACT, C-ACT, TRACK) pour d\u00e9terminer les changements dans le contr\u00f4le de l'asthme, le renforcement de l'\u00e9ducation de l'ASME et un rapport sur les progr\u00e8s et les am\u00e9liorations de l'environnement domestique du membre.<\/p><p>L'ASME doit \u00eatre dispens\u00e9e par un professionnel de sant\u00e9 non-m\u00e9decin qualifi\u00e9, tel qu'un \u00e9ducateur sp\u00e9cialis\u00e9 dans l'asthme (AE-C), un th\u00e9rapeute respiratoire (RT) ou un agent de sant\u00e9 non professionnel sp\u00e9cialement form\u00e9 (par exemple, un \u00e9ducateur de sant\u00e9, un agent de sant\u00e9 communautaire (CHW), etc.), ayant re\u00e7u une formation document\u00e9e et d\u00e9montr\u00e9 sa comp\u00e9tence \u00e0 dispenser une \u00e9ducation \u00e0 l'autogestion de l'asthme bas\u00e9e sur des lignes directrices et des \u00e9valuations compl\u00e8tes de l'environnement domestique afin d'identifier les d\u00e9clencheurs de l'asthme et de dispenser une \u00e9ducation \u00e0 leur r\u00e9duction.<\/p><p>Le prestataire de services d'ASME doit informer le navigateur de l'aide sociale si l'adh\u00e9rent a des besoins suppl\u00e9mentaires en mati\u00e8re de coordination des soins en dehors du service d'ASME (c'est-\u00e0-dire suivi clinique, etc.). Le prestataire de services ASME peut fournir des produits de soutien pour l'asthme et des produits de r\u00e9duction des allerg\u00e8nes int\u00e9rieurs et les facturer dans le cadre du plafond de l'adh\u00e9rent.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d533630 elementor-widget elementor-widget-button\" data-id=\"d533630\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/nyschildrensasthma.org\/fr\/nyher-resources\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Ressources li\u00e9es au volet A<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div id=\"e-n-tab-content-851132362\" role=\"tabpanel\" aria-labelledby=\"e-n-tab-title-851132362\" data-tab-index=\"2\" style=\"--n-tabs-title-order: 2;\" class=\"elementor-element elementor-element-1f07a12 e-con-full e-flex e-con e-child\" data-id=\"1f07a12\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-78747cb elementor-widget elementor-widget-heading\" data-id=\"78747cb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">\u00c9valuation des logements\n\u00c9laboration du cahier des charges (y compris l'examen technique du cahier des charges)<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4212157 elementor-widget elementor-widget-text-editor\" data-id=\"4212157\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><b>b.1 \u00c9valuation des logements et \u00e9laboration du cahier des charges :<\/b><span style=\"font-weight: 400;\">\u00a0<\/span><\/p><p><span style=\"font-weight: 400;\">Une \u00e9valuation compl\u00e8te de la r\u00e9sidence principale afin d'identifier les mesures correctives n\u00e9cessaires pour r\u00e9duire ou \u00e9liminer les d\u00e9clencheurs d'asthme et am\u00e9liorer l'environnement int\u00e9rieur de l'habitation doit \u00eatre effectu\u00e9e par un entrepreneur qualifi\u00e9 en am\u00e9lioration de l'habitat ayant les qualifications requises dans le domaine de la science du b\u00e2timent et des principes de l'habitat sain et incorporant les r\u00e9sultats et les conclusions environnementales pertinentes de la visite initiale de l'ASME.\u00a0<\/span><\/p><p><span style=\"font-weight: 400;\">Le cahier des charges doit d\u00e9crire les services de rem\u00e9diation recommand\u00e9s, les produits de soutien et les prix associ\u00e9s et doit \u00eatre approuv\u00e9 par le navigateur de l'aide sociale.\u00a0\u00a0<\/span><\/p><p><b>b.2 Examen technique du SOW :<\/b><span style=\"font-weight: 400;\">\u00a0<\/span><\/p><p><span style=\"font-weight: 400;\">Chaque cahier des charges doit faire l'objet d'un examen technique de la part d'un examinateur qualifi\u00e9 ayant des r\u00e9f\u00e9rences en mati\u00e8re de science du b\u00e2timent et de principes d'habitat sain, ind\u00e9pendant du prestataire de services HRSN charg\u00e9 de l'installation des mesures correctives approuv\u00e9es pour lutter contre l'asthme.\u00a0<\/span><\/p><p><span style=\"font-weight: 400;\">L'examen technique du cahier des charges doit permettre d'indiquer clairement dans le cahier des charges si les services recommand\u00e9s sont consid\u00e9r\u00e9s comme invasifs. Si le cahier des charges pr\u00e9voit des mesures invasives, l'accord \u00e9crit du propri\u00e9taire (bailleur dans le cas d'une location) doit \u00eatre obtenu par le navigateur de l'aide sociale et\/ou le fournisseur de la composante c. Remise en \u00e9tat du logement et fourniture de produits de soutien.<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-72439ba elementor-widget elementor-widget-button\" data-id=\"72439ba\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/nyschildrensasthma.org\/fr\/nyher-resources\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Ressources li\u00e9es au volet B<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div id=\"e-n-tab-content-851132363\" role=\"tabpanel\" aria-labelledby=\"e-n-tab-title-851132363\" data-tab-index=\"3\" style=\"--n-tabs-title-order: 3;\" class=\"elementor-element elementor-element-71454a8 e-con-full e-flex e-con e-child\" data-id=\"71454a8\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-890569a elementor-widget elementor-widget-heading\" data-id=\"890569a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Assainissement des habitations et fourniture de produits de soutien<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d707045 elementor-widget elementor-widget-text-editor\" data-id=\"d707045\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"font-weight: 400;\">Les services d'installation et les produits de soutien peuvent concerner la ventilation et la qualit\u00e9 de l'air, l'\u00e9limination des facteurs d\u00e9clenchant l'asthme et la lutte int\u00e9gr\u00e9e contre les parasites (IPM).  Les services d'assainissement et les produits de soutien seront limit\u00e9s \u00e0 la liste des services admissibles recommand\u00e9s dans le cahier des charges et approuv\u00e9s par le navigateur de l'aide sociale apr\u00e8s l'examen technique de la composante b.2 du cahier des charges.\u00a0\u00a0<\/span><\/p><p><span style=\"font-weight: 400;\">L'approbation \u00e9crite du membre est requise pour commencer l'installation des services approuv\u00e9s dans le cadre du SOW. Les services n\u00e9cessitant des mesures invasives doivent \u00eatre approuv\u00e9s par \u00e9crit par le propri\u00e9taire de la propri\u00e9t\u00e9 (le propri\u00e9taire, si la r\u00e9sidence est lou\u00e9e).\u00a0<\/span><\/p><p><span style=\"font-weight: 400;\">Les prestataires de services d'assainissement doivent fournir la preuve qu'ils poss\u00e8dent des titres, des autorisations d'exercer, des certifications et des formations accept\u00e9es par l'industrie (y compris les exigences avanc\u00e9es pour les services sp\u00e9cialis\u00e9s tels que le chauffage, la ventilation et la climatisation, la lutte int\u00e9gr\u00e9e contre les incendies, etc.) ET qu'ils ont de l'exp\u00e9rience dans l'identification et l'assainissement des facteurs environnementaux d\u00e9clencheurs de l'asthme \u00e0 domicile.<\/span><\/p><p><span style=\"font-weight: 400;\">Le co\u00fbt total des services de rem\u00e9diation de l'asthme ne doit pas d\u00e9passer le plafond par membre indiqu\u00e9 dans le bar\u00e8me des frais de HRSN pour la dur\u00e9e de la p\u00e9riode d'exemption.<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-04206ba elementor-widget elementor-widget-button\" data-id=\"04206ba\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/nyschildrensasthma.org\/fr\/nyher-resources\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Ressources li\u00e9es au volet C<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div id=\"e-n-tab-content-851132364\" role=\"tabpanel\" aria-labelledby=\"e-n-tab-title-851132364\" data-tab-index=\"4\" style=\"--n-tabs-title-order: 4;\" class=\"elementor-element elementor-element-eaa2243 e-flex e-con-boxed e-con e-child\" data-id=\"eaa2243\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-384ae2d elementor-widget elementor-widget-heading\" data-id=\"384ae2d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Assurance de la qualit\u00e9 (AQ) Inspection<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1ffd1c8 elementor-widget elementor-widget-text-editor\" data-id=\"1ffd1c8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"font-weight: 400;\">Dans les 90 jours suivant l'ach\u00e8vement du service, une inspection de l'assurance qualit\u00e9 doit \u00eatre effectu\u00e9e conform\u00e9ment aux normes techniques du Building Performance Institute (BPI) et d'autres secteurs d'activit\u00e9 pour au moins 10 % des m\u00e9nages o\u00f9 des services de rem\u00e9diation de l'asthme sont fournis par le RCS.\u00a0<\/span><\/p><p><span style=\"font-weight: 400;\">Le fournisseur de l'assurance qualit\u00e9 doit \u00eatre ind\u00e9pendant du fournisseur de l'\u00e9l\u00e9ment c. Remise en \u00e9tat du domicile et fourniture de produits de soutien.<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5f54ee8 elementor-widget elementor-widget-button\" data-id=\"5f54ee8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/nyschildrensasthma.org\/fr\/nyher-resources\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Ressources li\u00e9es au volet D<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-08300ed elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"08300ed\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-a8f3b13\" data-id=\"a8f3b13\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ff177b0 elementor-widget elementor-widget-heading\" data-id=\"ff177b0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Flux de travail pour la rem\u00e9diation de l'asthme<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-831a3d7 elementor-widget elementor-widget-image\" data-id=\"831a3d7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/nyschildrensasthma.org\/wp-content\/uploads\/2025\/03\/finalworkflowslide.png\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-title=\"finalworkflowslide\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6NTQ0MCwidXJsIjoiaHR0cHM6XC9cL255c2NoaWxkcmVuc2FzdGhtYS5vcmdcL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMjVcLzAzXC9maW5hbHdvcmtmbG93c2xpZGUucG5nIn0%3D\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"793\" height=\"448\" src=\"https:\/\/nyschildrensasthma.org\/wp-content\/uploads\/2025\/03\/finalworkflowslide.png\" class=\"attachment-large size-large wp-image-5440\" alt=\"\" srcset=\"https:\/\/nyschildrensasthma.org\/wp-content\/uploads\/2025\/03\/finalworkflowslide.png 793w, https:\/\/nyschildrensasthma.org\/wp-content\/uploads\/2025\/03\/finalworkflowslide-300x169.png 300w, https:\/\/nyschildrensasthma.org\/wp-content\/uploads\/2025\/03\/finalworkflowslide-768x434.png 768w\" sizes=\"(max-width: 793px) 100vw, 793px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t<div class=\"elementor-element elementor-element-c23e00f e-flex e-con-boxed e-con e-parent\" data-id=\"c23e00f\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-a1b8949 elementor-widget elementor-widget-heading\" data-id=\"a1b8949\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Services d'assainissement et produits de soutien admissibles<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d4cd187 elementor-widget elementor-widget-text-editor\" data-id=\"d4cd187\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><em>Les services d'att\u00e9nuation des sympt\u00f4mes de l'asthme et les produits de soutien sont limit\u00e9s \u00e0 ceux qui pr\u00e9sentent un avantage m\u00e9dical ou correctif direct pour l'adh\u00e9rent au programme Medicaid Managed Care.<\/em><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-67dfc82 elementor-widget elementor-widget-n-accordion\" data-id=\"67dfc82\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;default_state&quot;:&quot;expanded&quot;,&quot;max_items_expended&quot;:&quot;one&quot;,&quot;n_accordion_animation_duration&quot;:{&quot;unit&quot;:&quot;ms&quot;,&quot;size&quot;:400,&quot;sizes&quot;:[]}}\" data-widget_type=\"nested-accordion.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"e-n-accordion\" aria-label=\"Accord\u00e9on. Ouvrez les liens avec Enter ou Space, fermez-les avec Escape et naviguez avec les touches fl\u00e9ch\u00e9es.\">\n\t\t\t\t\t\t<details id=\"e-n-accordion-item-1080\" class=\"e-n-accordion-item\" open>\n\t\t\t\t<summary class=\"e-n-accordion-item-title\" data-accordion-index=\"1\" tabindex=\"0\" aria-expanded=\"true\" aria-controls=\"e-n-accordion-item-1080\" >\n\t\t\t\t\t<span class='e-n-accordion-item-title-header'><div class=\"e-n-accordion-item-title-text\"> Qualit\u00e9 de l'air int\u00e9rieur <\/div><\/span>\n\t\t\t\t\t\t\t\t\t<\/summary>\n\t\t\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-1080\" class=\"elementor-element elementor-element-2d9df6e e-con-full e-flex e-con e-child\" data-id=\"2d9df6e\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-1080\" class=\"elementor-element elementor-element-897beb9 e-con-full e-flex e-con e-child\" data-id=\"897beb9\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-430c571 elementor-widget elementor-widget-image\" data-id=\"430c571\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"184\" height=\"123\" src=\"https:\/\/nyschildrensasthma.org\/wp-content\/uploads\/2025\/01\/airquality.png\" class=\"attachment-large size-large wp-image-5231\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-1080\" class=\"elementor-element elementor-element-1a3fea5 e-con-full e-flex e-con e-child\" data-id=\"1a3fea5\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-61002eb elementor-widget elementor-widget-text-editor\" data-id=\"61002eb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>- Installation d'un climatiseur<br \/>- Am\u00e9lioration, installation et r\u00e9paration des syst\u00e8mes de ventilation<br \/>- Ventilateur d'ambiance<br \/>- Nettoyage et mise au point de l'unit\u00e9 de chauffage, r\u00e9parations ou remplacement<br \/>- Remplacement des filtres de la chaudi\u00e8re \u00e0 air puls\u00e9 et fourniture de (6) filtres suppl\u00e9mentaires<br \/>- Installation \/ r\u00e9paration d'un ventilateur d'extraction (cuisine et salle de bain)<br \/>- Ventilation et nettoyage des s\u00e8che-linge<br \/>- Entretien des conduits d'air<br \/>- Nettoyage de tapis \u00e0 la vapeur<br \/>- Isolation<br \/>- Etanch\u00e9it\u00e9 \u00e0 l'air<br \/>- Remplacement des filtres \u00e0 air du syst\u00e8me CVC<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/details>\n\t\t\t\t\t\t<details id=\"e-n-accordion-item-1081\" class=\"e-n-accordion-item\" >\n\t\t\t\t<summary class=\"e-n-accordion-item-title\" data-accordion-index=\"2\" tabindex=\"-1\" aria-expanded=\"false\" aria-controls=\"e-n-accordion-item-1081\" >\n\t\t\t\t\t<span class='e-n-accordion-item-title-header'><div class=\"e-n-accordion-item-title-text\"> Lutte contre les moisissures et l'humidit\u00e9 <\/div><\/span>\n\t\t\t\t\t\t\t\t\t<\/summary>\n\t\t\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-1081\" class=\"elementor-element elementor-element-73b8707 e-con-full e-flex e-con e-child\" data-id=\"73b8707\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-1081\" class=\"elementor-element elementor-element-aa9138a e-con-full e-flex e-con e-child\" data-id=\"aa9138a\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-560a249 elementor-widget elementor-widget-image\" data-id=\"560a249\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"187\" height=\"119\" src=\"https:\/\/nyschildrensasthma.org\/wp-content\/uploads\/2025\/01\/moldremed.png\" class=\"attachment-large size-large wp-image-5235\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-1081\" class=\"elementor-element elementor-element-7b7fcb1 e-con-full e-flex e-con e-child\" data-id=\"7b7fcb1\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-6239de9 elementor-widget elementor-widget-text-editor\" data-id=\"6239de9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>- R\u00e9paration de la plomberie pour lutter contre l'humidit\u00e9 et les d\u00e9g\u00e2ts des eaux<br \/>- R\u00e9paration des chaudi\u00e8res (vapeur et eau)<br \/>- R\u00e9paration de l'\u00e9vacuation des condensats<br \/>- Imperm\u00e9abilisation des sous-sols (rev\u00eatements, syst\u00e8mes de drainage)<br \/>- R\u00e9paration \/ remplacement de la pompe de relevage<br \/>- Enl\u00e8vement de la moquette ou des sols humides et moisis et installation d'un rev\u00eatement de sol sans danger pour l'asthme<br \/>- Sol en terre battue pare-vapeur sous-sol \/ vide sanitaire<br \/>- Nettoyage \/ r\u00e9paration \/ installation du syst\u00e8me de descente des goutti\u00e8res et des grilles de goutti\u00e8res<br \/>- Rem\u00e9diation aux moisissures (moins de 10 pieds carr\u00e9s)<br \/>- Rem\u00e9diation aux moisissures (plus de 10 pieds carr\u00e9s)<\/p><p><em>*Les travaux d'assainissement peuvent comprendre des travaux de finition (par exemple, pose de cloisons s\u00e8ches et peinture) pour rendre le logement habitable, mais ils ne comprennent pas les embellissements esth\u00e9tiques.<\/em><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/details>\n\t\t\t\t\t\t<details id=\"e-n-accordion-item-1082\" class=\"e-n-accordion-item\" >\n\t\t\t\t<summary class=\"e-n-accordion-item-title\" data-accordion-index=\"3\" tabindex=\"-1\" aria-expanded=\"false\" aria-controls=\"e-n-accordion-item-1082\" >\n\t\t\t\t\t<span class='e-n-accordion-item-title-header'><div class=\"e-n-accordion-item-title-text\"> R\u00e9duction des allerg\u00e8nes \u00e0 l'int\u00e9rieur <\/div><\/span>\n\t\t\t\t\t\t\t\t\t<\/summary>\n\t\t\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-1082\" class=\"elementor-element elementor-element-0e4e80a e-con-full e-flex e-con e-child\" data-id=\"0e4e80a\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-1082\" class=\"elementor-element elementor-element-08bf153 e-con-full e-flex e-con e-child\" data-id=\"08bf153\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-7fa275f elementor-widget elementor-widget-image\" data-id=\"7fa275f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"187\" height=\"118\" src=\"https:\/\/nyschildrensasthma.org\/wp-content\/uploads\/2025\/01\/indoor-1.png\" class=\"attachment-large size-large wp-image-5237\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-1082\" class=\"elementor-element elementor-element-0a30778 e-con-full e-flex e-con e-child\" data-id=\"0a30778\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-95f3937 elementor-widget elementor-widget-text-editor\" data-id=\"95f3937\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>- Aspirateur avec filtre HEPA et filtres de remplacement<br \/>- Enveloppe d'oreiller et de matelas imperm\u00e9able aux allerg\u00e8nes<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/details>\n\t\t\t\t\t\t<details id=\"e-n-accordion-item-1083\" class=\"e-n-accordion-item\" >\n\t\t\t\t<summary class=\"e-n-accordion-item-title\" data-accordion-index=\"4\" tabindex=\"-1\" aria-expanded=\"false\" aria-controls=\"e-n-accordion-item-1083\" >\n\t\t\t\t\t<span class='e-n-accordion-item-title-header'><div class=\"e-n-accordion-item-title-text\"> Nettoyage respectueux de l'asthme <\/div><\/span>\n\t\t\t\t\t\t\t\t\t<\/summary>\n\t\t\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-1083\" class=\"elementor-element elementor-element-7d947d4 e-con-full e-flex e-con e-child\" data-id=\"7d947d4\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-1083\" class=\"elementor-element elementor-element-4f89445 e-con-full e-flex e-con e-child\" data-id=\"4f89445\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-5bf88ed elementor-widget elementor-widget-image\" data-id=\"5bf88ed\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"184\" height=\"124\" src=\"https:\/\/nyschildrensasthma.org\/wp-content\/uploads\/2025\/01\/cleaning.png\" class=\"attachment-large size-large wp-image-5233\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-1083\" class=\"elementor-element elementor-element-0c54083 e-con-full e-flex e-con e-child\" data-id=\"0c54083\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-b6fac7c elementor-widget elementor-widget-text-editor\" data-id=\"b6fac7c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>- Hygrom\u00e8tre (Mesure de l'humidit\u00e9)<br \/>- Chiffons de nettoyage en microfibre<br \/>- Laveuses vertes<br \/>- Seaux de nettoyage et flacon pulv\u00e9risateur<br \/>- Mop en microfibre<br \/>- Savon de Castille<br \/>- Vinaigre de nettoyage (avec recette pour le m\u00e9lange)<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/details>\n\t\t\t\t\t\t<details id=\"e-n-accordion-item-1084\" class=\"e-n-accordion-item\" >\n\t\t\t\t<summary class=\"e-n-accordion-item-title\" data-accordion-index=\"5\" tabindex=\"-1\" aria-expanded=\"false\" aria-controls=\"e-n-accordion-item-1084\" >\n\t\t\t\t\t<span class='e-n-accordion-item-title-header'><div class=\"e-n-accordion-item-title-text\"> Lutte int\u00e9gr\u00e9e contre les ravageurs <\/div><\/span>\n\t\t\t\t\t\t\t\t\t<\/summary>\n\t\t\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-1084\" class=\"elementor-element elementor-element-2c4d7aa e-con-full e-flex e-con e-child\" data-id=\"2c4d7aa\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-1084\" class=\"elementor-element elementor-element-d099375 e-con-full e-flex e-con e-child\" data-id=\"d099375\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-85a79cf elementor-widget elementor-widget-image\" data-id=\"85a79cf\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"184\" height=\"122\" src=\"https:\/\/nyschildrensasthma.org\/wp-content\/uploads\/2025\/01\/pest.png\" class=\"attachment-large size-large wp-image-5232\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-1084\" class=\"elementor-element elementor-element-22063ae e-con-full e-flex e-con e-child\" data-id=\"22063ae\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-2403170 elementor-widget elementor-widget-text-editor\" data-id=\"2403170\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>- Sceller ou r\u00e9parer les fissures ou les ouvertures dans les murs, les plinthes et autour de la plomberie.<br \/>- Application de pesticides, d'app\u00e2ts et de pi\u00e8ges respectueux de l'environnement (\u00e0 utiliser hors de port\u00e9e des enfants et conform\u00e9ment aux instructions du fabricant)<br \/>- R\u00e9cipients herm\u00e9tiques pour la conservation des aliments<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/details>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-242f4e7 elementor-widget elementor-widget-text-editor\" data-id=\"242f4e7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><strong>Modifications de l'accessibilit\u00e9 et de la s\u00e9curit\u00e9 :<\/strong> Les climatiseurs, les humidificateurs et les appareils de filtration de l'air (limit\u00e9s aux appareils m\u00e9caniques uniquement) seront disponibles pour les membres \u00e9ligibles \u00e0 la rem\u00e9diation de l'asthme. Ces services seront financ\u00e9s au titre du point 2.2 \"Home Remediation Service\". Les membres peuvent \u00eatre \u00e9valu\u00e9s et jug\u00e9s \u00e9ligibles par un navigateur de l'aide sociale pour des services suppl\u00e9mentaires dans le cadre de 2.1 Modifications de l'accessibilit\u00e9 et de la s\u00e9curit\u00e9 du domicile et de 2.2 Services d'assainissement du domicile, les services seront li\u00e9s aux plafonds de financement correspondants.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1bf0515 elementor-widget elementor-widget-text-editor\" data-id=\"1bf0515\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><em>REMARQUE : les mesures de rem\u00e9diation contre l'asthme doivent \u00eatre prises conform\u00e9ment aux codes de construction locaux et nationaux en vigueur. <\/em><em>Les services n\u00e9cessitant des mesures invasives doivent \u00eatre approuv\u00e9s par \u00e9crit par le propri\u00e9taire du bien (le propri\u00e9taire, si la r\u00e9sidence est situ\u00e9e \u00e0 l'ext\u00e9rieur de la ville). <\/em><em>lou\u00e9).<\/em><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-679fdaa e-flex e-con-boxed e-con e-parent\" data-id=\"679fdaa\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-473e6a5 elementor-widget elementor-widget-heading\" data-id=\"473e6a5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Rem\u00e9diation \u00e0 l'asthme Fournisseurs HRSN<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1043c7c elementor-widget elementor-widget-text-editor\" data-id=\"1043c7c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><strong>Les fournisseurs autoris\u00e9s sont les suivants<\/strong><br \/>- Les fournisseurs de services d'assainissement de l'asthme sous contrat qui sont d\u00e9sign\u00e9s comme organisation communautaire \u00e0 but non lucratif 501(c)(3) ou 501(c)(4).<\/p><p>- Le service de rem\u00e9diation de l'asthme peut \u00eatre assur\u00e9 par une organisation \u00e0 but lucratif sous contrat, \u00e0 la discr\u00e9tion de l'entit\u00e9 chef de file du RCS, en l'absence d'une organisation communautaire 501(c)(3) ou 501(c)(4) disponible.<\/p><p><em>Voir le manuel d'exploitation du RCS pour plus de d\u00e9tails :<\/em><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4476ef8 elementor-widget elementor-widget-button\" data-id=\"4476ef8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/www.health.ny.gov\/health_care\/medicaid\/redesign\/sdh\/scn\/docs\/operations_manual.pdf\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Voir le manuel d'exploitation du RCS<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0f4f218 elementor-widget elementor-widget-shortcode\" data-id=\"0f4f218\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"shortcode.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-shortcode\">\n<table id=\"tablepress-3\" class=\"tablepress tablepress-id-3\">\n<thead>\n<tr class=\"row-1\">\n\t<th class=\"column-1\">Services HRSN<br \/>\nType de prestataire<\/th><th class=\"column-2\">Exigences de qualification<\/th><th class=\"column-3\">Consid\u00e9rations<\/th>\n<\/tr>\n<\/thead>\n<tbody class=\"row-striping row-hover\">\n<tr class=\"row-2\">\n\t<td class=\"column-1\">Asthme Self-<br \/>\nGestion<br \/>\nL'\u00e9ducation<br \/>\n(ASME) Fournisseur<br \/>\n(a.)<\/td><td class=\"column-2\">Professionnel de sant\u00e9 non-m\u00e9decin qualifi\u00e9 ayant une formation document\u00e9e et une comp\u00e9tence d\u00e9montr\u00e9e dans l'enseignement de l'autogestion de l'asthme bas\u00e9 sur des lignes directrices et dans l'\u00e9valuation compl\u00e8te de l'environnement domestique afin d'identifier et de fournir une \u00e9ducation sur la r\u00e9duction des d\u00e9clencheurs de l'asthme.<\/td><td class=\"column-3\">Exemples de prestataires ASME : \u00e9ducateur sp\u00e9cialis\u00e9 dans l'asthme certifi\u00e9 (AE-C), th\u00e9rapeute respiratoire (RT) et agent de sant\u00e9 non professionnel sp\u00e9cialement form\u00e9 (par exemple, \u00e9ducateur de sant\u00e9, CHW).<\/td>\n<\/tr>\n<tr class=\"row-3\">\n\t<td class=\"column-1\">Logement<br \/>\nAssesseur (b.1)<\/td><td class=\"column-2\">Entrepreneur qualifi\u00e9 pour l'am\u00e9lioration de l'habitat, avec des qualifications conformes aux normes de l'industrie dans le domaine de la science du b\u00e2timent et des principes de l'habitat sain.<\/td><td class=\"column-3\">Il peut s'agir du m\u00eame prestataire de services HRSN (entrepreneur de travaux d'am\u00e9lioration de l'habitat) qui r\u00e9alise le volet c. Remise en \u00e9tat de l'habitat et fourniture de produits de soutien.<\/td>\n<\/tr>\n<tr class=\"row-4\">\n\t<td class=\"column-1\">SOW technique<br \/>\nR\u00e9viseur (b.2)<\/td><td class=\"column-2\">R\u00e9viseur qualifi\u00e9 avec la norme de l'industrie<br \/>\nles dipl\u00f4mes en sciences du b\u00e2timent et en sant\u00e9<br \/>\nles principes des foyers travaillant ind\u00e9pendamment du prestataire de services HRSN (foyer<br \/>\n) effectuant l'installation d'un syst\u00e8me de contr\u00f4le de l'asthme (Asthma<br \/>\nMesures d'assainissement au titre du volet c.<\/td><td class=\"column-3\">Le r\u00e9viseur technique du cahier des charges doit travailler ind\u00e9pendamment du prestataire de services HRSN (entrepreneur en r\u00e9novation) charg\u00e9 de la composante c. Remise en \u00e9tat des habitations et fourniture de produits de soutien.<\/td>\n<\/tr>\n<tr class=\"row-5\">\n\t<td class=\"column-1\">Accueil<br \/>\nAm\u00e9lioration<br \/>\nEntrepreneur (c.)<\/td><td class=\"column-2\">Entrepreneur qualifi\u00e9 dans le domaine de l'am\u00e9lioration de l'habitat, justifiant de ses dipl\u00f4mes, de sa licence, de ses certifications et formations reconnues par le secteur (y compris les exigences avanc\u00e9es pour les services sp\u00e9cialis\u00e9s tels que le chauffage, la ventilation et la climatisation, l'IPA, l'\u00e9limination des moisissures, etc.) ET d'une exp\u00e9rience av\u00e9r\u00e9e dans l'installation de logements<br \/>\ndes services d'am\u00e9lioration de l'habitat, y compris l'identification et l'assainissement des logements li\u00e9s \u00e0 l'asthme<\/td><td class=\"column-3\">Il peut s'agir du m\u00eame prestataire de services HRSN (entrepreneur en r\u00e9novation) qui effectue l'\u00e9valuation du logement dans le cadre de l'\u00e9l\u00e9ment b.1.<\/td>\n<\/tr>\n<tr class=\"row-6\">\n\t<td class=\"column-1\">Qualit\u00e9<br \/>\nAssurance<br \/>\nInspecteur (d.)<\/td><td class=\"column-2\">Inspecteur qualifi\u00e9 poss\u00e9dant les qualifications requises par l'industrie en mati\u00e8re de science du b\u00e2timent et d'architecture.<br \/>\nles principes des maisons saines avec l'expertise n\u00e9cessaire pour mener une inspection d'assurance de la qualit\u00e9 en conformit\u00e9 avec les principes de l'assurance de la qualit\u00e9.<br \/>\nBuilding Performance Institute (BPI) et autres normes techniques du secteur pour l'assurance qualit\u00e9.<\/td><td class=\"column-3\">L'inspecteur de l'assurance qualit\u00e9 doit travailler ind\u00e9pendamment du prestataire de services HRSN (entrepreneur en r\u00e9novation) charg\u00e9 de la composante c. Remise en \u00e9tat des logements et fourniture de produits de soutien.<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<!-- #tablepress-3 from cache --><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-baff734 e-flex e-con-boxed e-con e-parent\" data-id=\"baff734\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-5cc8dc0 e-con-full e-flex e-con e-child\" data-id=\"5cc8dc0\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-da8ef07 elementor-widget elementor-widget-heading\" data-id=\"da8ef07\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Besoin d'une assistance technique ?<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c7df71a elementor-widget elementor-widget-text-editor\" data-id=\"c7df71a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Utilisez notre <a style=\"color: #d1e33b;\" href=\"https:\/\/nyschildrensasthma.org\/fr\/contact\/\">formulaire de contact<\/a> ou <a style=\"color: #d1e33b;\" href=\"mailto:NYSChildrensAsthmaInitiative@lung.org?subject=TA for NYHER Asthma Remediation\" target=\"_blank\" rel=\"noopener\">nous envoyer un courriel <\/a>pour entrer en contact avec un membre de l'\u00e9quipe du NYSCAI.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-110e4bd e-con-full e-flex e-con e-child\" data-id=\"110e4bd\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-7169afc elementor-widget elementor-widget-image\" data-id=\"7169afc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"219\" height=\"219\" src=\"https:\/\/nyschildrensasthma.org\/wp-content\/uploads\/2023\/09\/comp-blue.png\" class=\"attachment-large size-large wp-image-2644\" alt=\"\" srcset=\"https:\/\/nyschildrensasthma.org\/wp-content\/uploads\/2023\/09\/comp-blue.png 219w, https:\/\/nyschildrensasthma.org\/wp-content\/uploads\/2023\/09\/comp-blue-150x150.png 150w\" sizes=\"(max-width: 219px) 100vw, 219px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-a536a4a e-flex e-con-boxed e-con e-parent\" data-id=\"a536a4a\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-31c48568 elementor-widget elementor-widget-heading\" data-id=\"31c48568\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">En savoir plus sur les offres de NYHER et de rem\u00e9diation de l'asthme<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-1418ad74 e-con-full e-flex e-con e-parent\" data-id=\"1418ad74\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-6792f7bc e-con-full e-flex e-con e-child\" data-id=\"6792f7bc\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-58dedaa7 e-con-full e-flex e-con e-child\" data-id=\"58dedaa7\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-692db461 elementor-widget elementor-widget-heading\" data-id=\"692db461\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">R\u00e9seaux de soins sociaux (RCS)<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-63fce388 e-con-full e-flex e-con e-child\" data-id=\"63fce388\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-5504097e elementor-align-left elementor-mobile-align-center elementor-widget elementor-widget-button\" data-id=\"5504097e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm elementor-animation-grow\" href=\"https:\/\/nyschildrensasthma.org\/fr\/social-care-networks\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-arrow-alt-circle-right\" viewbox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M256 8c137 0 248 111 248 248S393 504 256 504 8 393 8 256 119 8 256 8zM140 300h116v70.9c0 10.7 13 16.1 20.5 8.5l114.3-114.9c4.7-4.7 4.7-12.2 0-16.9l-114.3-115c-7.6-7.6-20.5-2.2-20.5 8.5V212H140c-6.6 0-12 5.4-12 12v64c0 6.6 5.4 12 12 12z\"><\/path><\/svg>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">En savoir plus<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-7ed4971b e-con-full e-flex e-con e-child\" data-id=\"7ed4971b\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-64fc5dec e-con-full e-flex e-con e-child\" data-id=\"64fc5dec\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-62531600 e-con-full e-flex e-con e-child\" data-id=\"62531600\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-7112a6c9 elementor-widget elementor-widget-heading\" data-id=\"7112a6c9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Services relatifs aux besoins sociaux li\u00e9s \u00e0 la sant\u00e9 (HRSN)<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-11f12c0b e-con-full e-flex e-con e-child\" data-id=\"11f12c0b\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-6ca7dc0e elementor-align-left elementor-mobile-align-center elementor-widget elementor-widget-button\" data-id=\"6ca7dc0e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm elementor-animation-grow\" href=\"https:\/\/nyschildrensasthma.org\/fr\/hrsn-services\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-arrow-alt-circle-right\" viewbox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M256 8c137 0 248 111 248 248S393 504 256 504 8 393 8 256 119 8 256 8zM140 300h116v70.9c0 10.7 13 16.1 20.5 8.5l114.3-114.9c4.7-4.7 4.7-12.2 0-16.9l-114.3-115c-7.6-7.6-20.5-2.2-20.5 8.5V212H140c-6.6 0-12 5.4-12 12v64c0 6.6 5.4 12 12 12z\"><\/path><\/svg>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">En savoir plus<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-7ff6fb42 e-con-full e-flex e-con e-child\" data-id=\"7ff6fb42\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-554b7bab e-con-full e-flex e-con e-child\" data-id=\"554b7bab\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-57937606 e-con-full e-flex e-con e-child\" data-id=\"57937606\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-7bbab672 elementor-widget elementor-widget-heading\" data-id=\"7bbab672\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\"><a href=\"https:\/\/nyschildrensasthma.org\/fr\/asthma-remediation-hrsn-services\/\">Rem\u00e9diation \u00e0 l'asthme Services HRSN am\u00e9lior\u00e9s<\/a><\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-36e73c12 e-con-full e-flex e-con e-child\" data-id=\"36e73c12\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-9143f7c elementor-align-left elementor-mobile-align-center elementor-widget elementor-widget-button\" data-id=\"9143f7c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm elementor-animation-grow\" href=\"https:\/\/nyschildrensasthma.org\/fr\/asthma-remediation-hrsn-services\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-arrow-alt-circle-right\" viewbox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M256 8c137 0 248 111 248 248S393 504 256 504 8 393 8 256 119 8 256 8zM140 300h116v70.9c0 10.7 13 16.1 20.5 8.5l114.3-114.9c4.7-4.7 4.7-12.2 0-16.9l-114.3-115c-7.6-7.6-20.5-2.2-20.5 8.5V212H140c-6.6 0-12 5.4-12 12v64c0 6.6 5.4 12 12 12z\"><\/path><\/svg>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">En savoir plus<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-5b629bb5 e-con-full e-flex e-con e-child\" data-id=\"5b629bb5\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-5b63c347 e-con-full e-flex e-con e-child\" data-id=\"5b63c347\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-22bb7570 e-con-full e-flex e-con e-child\" data-id=\"22bb7570\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-46188c7e elementor-widget elementor-widget-heading\" data-id=\"46188c7e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Ressources et formation<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-5bc91b95 e-con-full e-flex e-con e-child\" data-id=\"5bc91b95\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-185d3244 elementor-align-left elementor-mobile-align-center elementor-widget elementor-widget-button\" data-id=\"185d3244\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm elementor-animation-grow\" href=\"https:\/\/nyschildrensasthma.org\/fr\/nyher-resources\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-arrow-alt-circle-right\" viewbox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M256 8c137 0 248 111 248 248S393 504 256 504 8 393 8 256 119 8 256 8zM140 300h116v70.9c0 10.7 13 16.1 20.5 8.5l114.3-114.9c4.7-4.7 4.7-12.2 0-16.9l-114.3-115c-7.6-7.6-20.5-2.2-20.5 8.5V212H140c-6.6 0-12 5.4-12 12v64c0 6.6 5.4 12 12 12z\"><\/path><\/svg>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">En savoir plus<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-4eed1138 e-con-full e-flex e-con e-child\" data-id=\"4eed1138\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-9d6a074 e-flex e-con-boxed e-con e-parent\" data-id=\"9d6a074\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-670df1c0 elementor-widget elementor-widget-heading\" data-id=\"670df1c0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Des questions ?<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-60a37d7f elementor-widget-mobile__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"60a37d7f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<ul><li>Les demandes et\/ou les commentaires relatifs \u00e0 NYHER et aux r\u00e9seaux de soins sociaux peuvent \u00eatre envoy\u00e9s par courrier \u00e9lectronique \u00e0 l'adresse suivante <a href=\"mailto:SDH@health.ny.gov\" target=\"_blank\" rel=\"noopener\">SDH@health.ny.gov<\/a><\/li><li>L'American Lung Association est disponible dans le cadre de la NYS Children's Asthma Initiative pour fournir une assistance technique li\u00e9e aux services HRSN de NYHER pour la rem\u00e9diation de l'asthme. Pour plus d'informations, utilisez notre <a href=\"https:\/\/nyschildrensasthma.org\/fr\/contact\/\">formulaire de contact<\/a> ou envoyer un courriel \u00e0 la NYSCAI <a href=\"mailto:NYSChildrensAsthmaInitiative@lung.org?subject=TA for NYHER Asthma Remediation\" target=\"_blank\" rel=\"noopener\">ici.<\/a><\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>Services de rem\u00e9diation de l'asthme HRSN NYHER Les Services de rem\u00e9diation de l'asthme sont con\u00e7us pour adresser de multiples d\u00e9clencheurs environnementaux de l'asthme \u00e0 domicile afin d'am\u00e9liorer la r\u00e9sidence du membre b\u00e9n\u00e9ficiaire et sa capacit\u00e9 \u00e0 g\u00e9rer l'asthme de mani\u00e8re autonome. Les composantes comprennent la prestation d'\u00e9ducation \u00e0 l'autogestion de l'asthme, la prestation de services de rem\u00e9diation pour \u00e9liminer les allerg\u00e8nes environnementaux int\u00e9rieurs, et la diffusion de produits de soutien pour \u00e9liminer ou r\u00e9duire les d\u00e9clencheurs de l'asthme [\u2026]<\/p>","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-5115","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Asthma Remediation HRSN Services &#8211; New York State Childrens Asthma Initiative<\/title>\n<meta name=\"description\" content=\"We partner with home-based service organizations across New York State to provide asthma home visits to children with asthma.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/nyschildrensasthma.org\/fr\/asthma-remediation-hrsn-services\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Asthma Remediation HRSN Services &#8211; New York State Childrens Asthma Initiative\" \/>\n<meta property=\"og:description\" content=\"We partner with home-based service organizations across New York State to provide asthma home visits to children with asthma.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/nyschildrensasthma.org\/fr\/asthma-remediation-hrsn-services\/\" \/>\n<meta property=\"og:site_name\" content=\"New York State Childrens Asthma Initiative\" \/>\n<meta property=\"article:modified_time\" content=\"2026-04-28T14:03:42+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/nyschildrensasthma.org\/wp-content\/uploads\/2025\/01\/2148457028.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"674\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/nyschildrensasthma.org\/en\/asthma-remediation-hrsn-services\/\",\"url\":\"https:\/\/nyschildrensasthma.org\/en\/asthma-remediation-hrsn-services\/\",\"name\":\"Asthma Remediation HRSN Services &#8211; New York State Childrens Asthma Initiative\",\"isPartOf\":{\"@id\":\"https:\/\/nyschildrensasthmainitiative.com\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/nyschildrensasthma.org\/en\/asthma-remediation-hrsn-services\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/nyschildrensasthma.org\/en\/asthma-remediation-hrsn-services\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/nyschildrensasthma.org\/wp-content\/uploads\/2025\/01\/2148457028-768x518.jpg\",\"datePublished\":\"2025-01-23T21:39:49+00:00\",\"dateModified\":\"2026-04-28T14:03:42+00:00\",\"description\":\"We partner with home-based service organizations across New York State to provide asthma home visits to children with asthma.\",\"breadcrumb\":{\"@id\":\"https:\/\/nyschildrensasthma.org\/en\/asthma-remediation-hrsn-services\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/nyschildrensasthma.org\/en\/asthma-remediation-hrsn-services\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/nyschildrensasthma.org\/en\/asthma-remediation-hrsn-services\/#primaryimage\",\"url\":\"https:\/\/nyschildrensasthma.org\/wp-content\/uploads\/2025\/01\/2148457028-768x518.jpg\",\"contentUrl\":\"https:\/\/nyschildrensasthma.org\/wp-content\/uploads\/2025\/01\/2148457028-768x518.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/nyschildrensasthma.org\/en\/asthma-remediation-hrsn-services\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/nyschildrensasthma.org\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Asthma Remediation HRSN Services\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/nyschildrensasthmainitiative.com\/#website\",\"url\":\"https:\/\/nyschildrensasthmainitiative.com\/\",\"name\":\"New York State Children's Asthma Initiative\",\"description\":\"Providing guidelines-based care for schools and children with asthma in New York State\",\"publisher\":{\"@id\":\"https:\/\/nyschildrensasthmainitiative.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/nyschildrensasthmainitiative.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/nyschildrensasthmainitiative.com\/#organization\",\"name\":\"New York State Children's Asthma Initiative\",\"url\":\"https:\/\/nyschildrensasthmainitiative.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/nyschildrensasthmainitiative.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/nyschildrensasthma.org\/wp-content\/uploads\/2023\/08\/cropped-FY23-NYS-CAI-Logo_Horiz_Digital-e1692113998994.png\",\"contentUrl\":\"https:\/\/nyschildrensasthma.org\/wp-content\/uploads\/2023\/08\/cropped-FY23-NYS-CAI-Logo_Horiz_Digital-e1692113998994.png\",\"width\":544,\"height\":141,\"caption\":\"New York State Children's Asthma Initiative\"},\"image\":{\"@id\":\"https:\/\/nyschildrensasthmainitiative.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Asthma Remediation HRSN Services - New York State Childrens Asthma Initiative (Initiative pour l'asthme chez les enfants)","description":"Nous travaillons en partenariat avec des organisations de services \u00e0 domicile dans tout l'\u00c9tat de New York pour fournir des visites \u00e0 domicile aux enfants asthmatiques.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/nyschildrensasthma.org\/fr\/asthma-remediation-hrsn-services\/","og_locale":"fr_FR","og_type":"article","og_title":"Asthma Remediation HRSN Services &#8211; New York State Childrens Asthma Initiative","og_description":"We partner with home-based service organizations across New York State to provide asthma home visits to children with asthma.","og_url":"https:\/\/nyschildrensasthma.org\/fr\/asthma-remediation-hrsn-services\/","og_site_name":"New York State Childrens Asthma Initiative","article_modified_time":"2026-04-28T14:03:42+00:00","og_image":[{"width":1000,"height":674,"url":"https:\/\/nyschildrensasthma.org\/wp-content\/uploads\/2025\/01\/2148457028.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/nyschildrensasthma.org\/en\/asthma-remediation-hrsn-services\/","url":"https:\/\/nyschildrensasthma.org\/en\/asthma-remediation-hrsn-services\/","name":"Asthma Remediation HRSN Services - New York State Childrens Asthma Initiative (Initiative pour l'asthme chez les enfants)","isPartOf":{"@id":"https:\/\/nyschildrensasthmainitiative.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/nyschildrensasthma.org\/en\/asthma-remediation-hrsn-services\/#primaryimage"},"image":{"@id":"https:\/\/nyschildrensasthma.org\/en\/asthma-remediation-hrsn-services\/#primaryimage"},"thumbnailUrl":"https:\/\/nyschildrensasthma.org\/wp-content\/uploads\/2025\/01\/2148457028-768x518.jpg","datePublished":"2025-01-23T21:39:49+00:00","dateModified":"2026-04-28T14:03:42+00:00","description":"Nous travaillons en partenariat avec des organisations de services \u00e0 domicile dans tout l'\u00c9tat de New York pour fournir des visites \u00e0 domicile aux enfants asthmatiques.","breadcrumb":{"@id":"https:\/\/nyschildrensasthma.org\/en\/asthma-remediation-hrsn-services\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/nyschildrensasthma.org\/en\/asthma-remediation-hrsn-services\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/nyschildrensasthma.org\/en\/asthma-remediation-hrsn-services\/#primaryimage","url":"https:\/\/nyschildrensasthma.org\/wp-content\/uploads\/2025\/01\/2148457028-768x518.jpg","contentUrl":"https:\/\/nyschildrensasthma.org\/wp-content\/uploads\/2025\/01\/2148457028-768x518.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/nyschildrensasthma.org\/en\/asthma-remediation-hrsn-services\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/nyschildrensasthma.org\/"},{"@type":"ListItem","position":2,"name":"Asthma Remediation HRSN Services"}]},{"@type":"WebSite","@id":"https:\/\/nyschildrensasthmainitiative.com\/#website","url":"https:\/\/nyschildrensasthmainitiative.com\/","name":"Initiative de l'\u00c9tat de New York sur l'asthme chez les enfants","description":"Fournir des soins bas\u00e9s sur des lignes directrices pour les \u00e9coles et les enfants asthmatiques dans l'\u00c9tat de New York","publisher":{"@id":"https:\/\/nyschildrensasthmainitiative.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/nyschildrensasthmainitiative.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/nyschildrensasthmainitiative.com\/#organization","name":"Initiative de l'\u00c9tat de New York sur l'asthme chez les enfants","url":"https:\/\/nyschildrensasthmainitiative.com\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/nyschildrensasthmainitiative.com\/#\/schema\/logo\/image\/","url":"https:\/\/nyschildrensasthma.org\/wp-content\/uploads\/2023\/08\/cropped-FY23-NYS-CAI-Logo_Horiz_Digital-e1692113998994.png","contentUrl":"https:\/\/nyschildrensasthma.org\/wp-content\/uploads\/2023\/08\/cropped-FY23-NYS-CAI-Logo_Horiz_Digital-e1692113998994.png","width":544,"height":141,"caption":"New York State Children's Asthma Initiative"},"image":{"@id":"https:\/\/nyschildrensasthmainitiative.com\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/nyschildrensasthma.org\/fr\/wp-json\/wp\/v2\/pages\/5115","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/nyschildrensasthma.org\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/nyschildrensasthma.org\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/nyschildrensasthma.org\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/nyschildrensasthma.org\/fr\/wp-json\/wp\/v2\/comments?post=5115"}],"version-history":[{"count":25,"href":"https:\/\/nyschildrensasthma.org\/fr\/wp-json\/wp\/v2\/pages\/5115\/revisions"}],"predecessor-version":[{"id":6989,"href":"https:\/\/nyschildrensasthma.org\/fr\/wp-json\/wp\/v2\/pages\/5115\/revisions\/6989"}],"wp:attachment":[{"href":"https:\/\/nyschildrensasthma.org\/fr\/wp-json\/wp\/v2\/media?parent=5115"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}